{"id":2639,"date":"2015-11-24T14:35:27","date_gmt":"2015-11-24T14:35:27","guid":{"rendered":"https:\/\/nova.elfornerdealella.com\/?p=2639"},"modified":"2024-04-29T11:33:57","modified_gmt":"2024-04-29T09:33:57","slug":"lluc-al-forn-amb-gules-i-gambes","status":"publish","type":"post","link":"https:\/\/elfornerdealella.com\/ca\/merluza-al-horno-con-gulas-y-gambas\/","title":{"rendered":"Llu\u00e7 al Forn amb Gules i Gambes"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Carmen al Forner d&#039;Alella ens prepara una recepta de Llu\u00e7 al Forn amb Gulas y Gambas que \u00e9s un plat molt apropiat per a alguna celebraci\u00f3 ja que \u00e9s molt r\u00e0pid i f\u00e0cil de preparar i que segur que triomfeu si ho feu a casa. Si us agrada aquest v\u00eddeo de Llu\u00e7 amb Gulas i Gambas puntua&#039;l i compartir-lo.<br>D\u00f3na-li al play i gaudeix del v\u00eddeo del Llu\u00e7 al Forn amb Gulas i Gambas.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Llu\u00e7 al forn amb Gulas i Gambas\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-6fNR8MGINM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">INGREDIENTS:<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>4 Rodanxes gruixudes de Llu\u00e7<\/li><li>125 grs. Gules<\/li><li>125 grs. Gambes pelades congelades<\/li><li>4 Dents d&#039;All<\/li><li>2 Caienes (Guindillas)<\/li><li>Oli d&#039;Oliva<\/li><li>Sal i Pebre negre<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">ELABORACI\u00d3:<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Salpebrem el llu\u00e7 pels dos costats. Posarem les rodanxes de llu\u00e7 en una safata que pugui anar al forn.<\/li><li>Ruixem el llu\u00e7 amb una mica d&#039;oli i el coem al forn preescalfat a 200 \u00ba cent\u00edgrads per dalt i baix durant uns 20 minuts aproximadament. Dep\u00e8n del gust de cadasc\u00fa, \u00e9s millor que no quedi gaire cuit.<\/li><li>En una paella petita hi posem l&#039;oli d&#039;oliva i ho escalfem una mica. Hi afegim els alls laminats ia foc molt lent confitarem els alls.<\/li><li>Afegirem les gambes, els bitxos trossejats i la sal. Deixarem coure tot junt durant uns 2 minuts.<\/li><li>Per servir el plat posarem una rodanxa de llu\u00e7 i per sobre el refregit de gambes i gules amb una mica de l&#039;oli de fregir.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Us aconsello que veieu el v\u00eddeo Llu\u00e7 al Forn amb Gulas i Gambas per a una millor comprensi\u00f3 de tot el que he explicat.<\/b><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/elfornerdealella.com\/wp-content\/uploads\/2021\/03\/Merluza-al-horno-con-Gulas-y-Gambas111.jpg\" alt=\"Recepta de\" data-id=\"6197\" class=\"wp-image-6197\" title=\"Recepta de\"><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/elfornerdealella.com\/wp-content\/uploads\/2021\/03\/Merluza-al-horno-con-Gulas-y-Gambas14.jpg\" alt=\"Recepta de\" data-id=\"6188\" class=\"wp-image-6188\" title=\"Recepta de\"><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/elfornerdealella.com\/wp-content\/uploads\/2021\/03\/Merluza-al-horno-con-Gulas-y-Gambas15.jpg\" alt=\"Recepta de\" data-id=\"6189\" class=\"wp-image-6189\" title=\"Recepta de\"><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/elfornerdealella.com\/wp-content\/uploads\/2021\/03\/Merluza-al-horno-con-Gulas-y-Gambas18.jpg\" alt=\"Recepta de\" data-id=\"6190\" class=\"wp-image-6190\" title=\"Recepta de\"><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/elfornerdealella.com\/wp-content\/uploads\/2021\/03\/Merluza-al-horno-con-Gulas-y-Gambas22.jpg\" alt=\"Recepta de\" data-id=\"6191\" class=\"wp-image-6191\" title=\"Recepta de\"><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/elfornerdealella.com\/wp-content\/uploads\/2021\/03\/Merluza-al-horno-con-Gulas-y-Gambas28.jpg\" alt=\"Recepta de\" data-id=\"6193\" class=\"wp-image-6193\" title=\"Recepta de\"><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/elfornerdealella.com\/wp-content\/uploads\/2021\/03\/Merluza-al-horno-con-Gulas-y-Gambas31.jpg\" alt=\"Recepta de\" data-id=\"6194\" class=\"wp-image-6194\" title=\"Recepta de\"><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/elfornerdealella.com\/wp-content\/uploads\/2021\/03\/Merluza-al-horno-con-Gulas-y-Gambas.jpg\" alt=\"Recepta de\" data-id=\"6186\" class=\"wp-image-6186\" title=\"Recepta de\"><\/figure><\/li><\/ul><\/figure>","protected":false},"excerpt":{"rendered":"<p>Carmen en el Forner de Alella nos prepara una receta de Merluza al Horno con Gulas y Gambas que es un plato muy apropiado para alguna celebraci\u00f3n ya que es muy r\u00e1pido y f\u00e1cil de preparar y que seguro que triunf\u00e1is si lo hac\u00e9is en casa. Si os gusta este v\u00eddeo de Merluza con Gulas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[92,20,93],"tags":[210,2447,2448,2449,2450,2451,1004],"class_list":["post-2639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-segundos-platos-caseros","category-recetas-de-navidad","category-segundos-platos-navidad","tag-como-preparar-merluza","tag-como-preparar-merluza-al-horno","tag-merluza-al-horno-con-gulas-y-gambas","tag-merluza-para-fiestas","tag-preparar-merluza","tag-receta-de-merluza","tag-receta-tradicional-merluza"],"_links":{"self":[{"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/posts\/2639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/comments?post=2639"}],"version-history":[{"count":2,"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/posts\/2639\/revisions"}],"predecessor-version":[{"id":11314,"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/posts\/2639\/revisions\/11314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/media\/11310"}],"wp:attachment":[{"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/media?parent=2639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/categories?post=2639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfornerdealella.com\/ca\/wp-json\/wp\/v2\/tags?post=2639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}